{"id":13135,"date":"2024-02-06T16:30:17","date_gmt":"2024-02-06T15:30:17","guid":{"rendered":"https:\/\/www.mirkozago.it\/story\/boho-chic-2\/"},"modified":"2024-06-25T13:01:58","modified_gmt":"2024-06-25T11:01:58","slug":"boho-chic-2","status":"publish","type":"story","link":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/","title":{"rendered":"Boho Chic"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull has-custom-content-position is-position-bottom-center\" style=\"padding-right:15px;padding-left:15px;min-height:66vh\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-100 has-background-dim wp-block-cover__gradient-background has-background-gradient\" style=\"background:linear-gradient(1deg, rgba(0, 0, 0, 0.75) 12.35%, rgba(0, 0, 0, 0.00) 98.82%)\"><\/span><img decoding=\"async\" width=\"2200\" height=\"1467\" class=\"wp-block-cover__image-background wp-image-11818\" alt=\"\" src=\"https:\/\/mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg\" style=\"object-position:52% 54%\" data-object-fit=\"cover\" data-object-position=\"52% 54%\" srcset=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg 2200w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-600x400.jpg 600w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-1440x960.jpg 1440w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-1024x683.jpg 1024w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-1536x1024.jpg 1536w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-2048x1366.jpg 2048w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-70x47.jpg 70w, https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover-1920x1280.jpg 1920w\" sizes=\"(max-width: 2200px) 100vw, 2200px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-group thor-maxwidth-4xl is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-group__inner-container\">\n<h1 class=\"wp-block-heading has-text-align-left has-5-xl-font-size\">Boho Chic Wedding<\/h1>\n\n\n<p>[rank_math_breadcrumb]<\/p>\n\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer thor-hidden-sm\"><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-group alignfull thor-maxwidth-default has-primary-400-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-group thor-maxwidth-xl is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-group__inner-container\">\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer thor-hidden-sm\"><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"\">THE STORY OF<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-4-xl-font-size\">Gianni and Yssana<\/h2>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"\">This destination wedding with a couple from Zurich put me to the test, with a very demanding bride and only 4 months to do everything. The result? An incredible wedding, with decorations, ceremony, and color palette, all being very original and with a perfect mix of balance between modern, retro, and vintage.<br\/>I believe it&#8217;s one of my favorites in recent years. It feels like Provence or Tuscany, instead of&#8230; enjoy!<\/p>\n\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer thor-hidden-sm\"><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group thor-maxwidth-4xl is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-group__inner-container\"><div  class=\"thor-story-gallery\">\n    <div class=\"gallery-inner\">\n        <div class=\"row\">\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-157-1440x1072.jpg\"\n                        data-title=\"villa-cipressi-mirko--157\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-157-600x447.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/PAOLO-1.00_47_57_33.Immagine059-1-1440x810.jpg\"\n                        data-title=\"PAOLO-1.00_47_57_33.Immagine059\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/PAOLO-1.00_47_57_33.Immagine059-1-600x338.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-154-1440x960.jpg\"\n                        data-title=\"villa-cipressi-mirko--154\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-154-600x400.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/Destination-wedding-boho-chic-itlay-2.jpg\"\n                        data-title=\"Destination-wedding-boho-chic-itlay-2\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/Destination-wedding-boho-chic-itlay-2-600x900.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-449.jpg\"\n                        data-title=\"villa-cipressi-mirko--449\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-449-600x900.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-524.jpg\"\n                        data-title=\"villa-cipressi-mirko--524\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-524-600x900.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-251.jpg\"\n                        data-title=\"villa-cipressi-mirko--251\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-251-600x900.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-401-1440x960.jpg\"\n                        data-title=\"villa-cipressi-mirko--401\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-401-600x400.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-28-1440x960.jpg\"\n                        data-title=\"villa-cipressi-mirko--28\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-28-600x400.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-462.jpg\"\n                        data-title=\"villa-cipressi-mirko--462\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-462-600x900.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-519-1440x960.jpg\"\n                        data-title=\"villa-cipressi-mirko--519\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-519-600x400.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-508.jpg\"\n                        data-title=\"villa-cipressi-mirko--508\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-508-600x900.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-463-1440x960.jpg\"\n                        data-title=\"villa-cipressi-mirko--463\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-463-600x400.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                            <div class=\"image-wrapper w-1\/2 md:w-1\/3\">\n                    <a \n                        href=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-536-1440x960.jpg\"\n                        data-title=\"villa-cipressi-mirko--536\"\n                        data-description=\"\"\n                        class=\"glightbox\"\n                    >\n                        <figure>\n                            <img decoding=\"async\" src=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-536-600x400.jpg\" alt=\"\" \/>\n                        <\/figure>\n                    <\/a>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div style=\"height:70px\" aria-hidden=\"true\" class=\"wp-block-spacer thor-hidden-sm\"><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"author":3,"featured_media":13073,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boho Chic - Mirko Zago - Wedding Planner a Verona e Lago di Garda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boho Chic - Mirko Zago - Wedding Planner a Verona e Lago di Garda\" \/>\n<meta property=\"og:description\" content=\"THE STORY OF Gianni and Yssana This destination wedding with a couple from Zurich put me to the test, with...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Mirko Zago - Wedding Planner a Verona e Lago di Garda\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-25T11:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/\",\"url\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/\",\"name\":\"Boho Chic - Mirko Zago - Wedding Planner a Verona e Lago di Garda\",\"isPartOf\":{\"@id\":\"https:\/\/www.mirkozago.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg\",\"datePublished\":\"2024-02-06T15:30:17+00:00\",\"dateModified\":\"2024-06-25T11:01:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#primaryimage\",\"url\":\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg\",\"contentUrl\":\"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg\",\"width\":2200,\"height\":1467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mirkozago.it\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boho Chic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mirkozago.it\/en\/#website\",\"url\":\"https:\/\/www.mirkozago.it\/en\/\",\"name\":\"Mirko Zago - Wedding Planner a Verona e Lago di Garda\",\"description\":\"Sono Mirko Zago e mi occupo di organizzazione di matrimoni sul lago di Garda e lago di Como. Entra nel mio mondo e scopri di pi\u00f9 sul mio lavoro!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mirkozago.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boho Chic - Mirko Zago - Wedding Planner a Verona e Lago di Garda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/","og_locale":"en_US","og_type":"article","og_title":"Boho Chic - Mirko Zago - Wedding Planner a Verona e Lago di Garda","og_description":"THE STORY OF Gianni and Yssana This destination wedding with a couple from Zurich put me to the test, with...","og_url":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/","og_site_name":"Mirko Zago - Wedding Planner a Verona e Lago di Garda","article_modified_time":"2024-06-25T11:01:58+00:00","og_image":[{"width":2200,"height":1467,"url":"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/","url":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/","name":"Boho Chic - Mirko Zago - Wedding Planner a Verona e Lago di Garda","isPartOf":{"@id":"https:\/\/www.mirkozago.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#primaryimage"},"image":{"@id":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg","datePublished":"2024-02-06T15:30:17+00:00","dateModified":"2024-06-25T11:01:58+00:00","breadcrumb":{"@id":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#primaryimage","url":"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg","contentUrl":"https:\/\/www.mirkozago.it\/web\/app\/uploads\/2024\/02\/villa-cipressi-mirko-482-cover.jpg","width":2200,"height":1467},{"@type":"BreadcrumbList","@id":"https:\/\/www.mirkozago.it\/en\/story\/boho-chic-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mirkozago.it\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Boho Chic"}]},{"@type":"WebSite","@id":"https:\/\/www.mirkozago.it\/en\/#website","url":"https:\/\/www.mirkozago.it\/en\/","name":"Mirko Zago - Wedding Planner a Verona e Lago di Garda","description":"Sono Mirko Zago e mi occupo di organizzazione di matrimoni sul lago di Garda e lago di Como. Entra nel mio mondo e scopri di pi\u00f9 sul mio lavoro!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mirkozago.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.mirkozago.it\/en\/wp-json\/wp\/v2\/story\/13135"}],"collection":[{"href":"https:\/\/www.mirkozago.it\/en\/wp-json\/wp\/v2\/story"}],"about":[{"href":"https:\/\/www.mirkozago.it\/en\/wp-json\/wp\/v2\/types\/story"}],"author":[{"embeddable":true,"href":"https:\/\/www.mirkozago.it\/en\/wp-json\/wp\/v2\/users\/3"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mirkozago.it\/en\/wp-json\/wp\/v2\/media\/13073"}],"wp:attachment":[{"href":"https:\/\/www.mirkozago.it\/en\/wp-json\/wp\/v2\/media?parent=13135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}